{"id":1040,"count":13,"description":"","link":"https:\/\/orer.eu\/hy\/tag\/%d5%ad%d5%a1%d5%b9%d6%84%d5%a1%d6%80\/","name":"\u056d\u0561\u0579\u0584\u0561\u0580","slug":"%d5%ad%d5%a1%d5%b9%d6%84%d5%a1%d6%80","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/orer.eu\/hy\/wp-json\/wp\/v2\/tags\/1040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orer.eu\/hy\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/orer.eu\/hy\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/orer.eu\/hy\/wp-json\/wp\/v2\/posts?tags=1040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}