{"id":1277,"count":2,"description":"","link":"https:\/\/orer.eu\/cs\/tag\/emmanuel-tjeknavorian\/","name":"Emmanuel Tjeknavorian","slug":"emmanuel-tjeknavorian","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/orer.eu\/cs\/wp-json\/wp\/v2\/tags\/1277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orer.eu\/cs\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/orer.eu\/cs\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/orer.eu\/cs\/wp-json\/wp\/v2\/posts?tags=1277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}